{"id":12152,"date":"2026-05-13T00:02:34","date_gmt":"2026-05-12T22:02:34","guid":{"rendered":"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/"},"modified":"2026-05-13T00:02:34","modified_gmt":"2026-05-12T22:02:34","slug":"responsable-atelier","status":"publish","type":"offresdemploi","link":"https:\/\/werthanor.ch\/en\/offre-d-emploi\/responsable-atelier\/","title":{"rendered":"Responsable atelier"},"content":{"rendered":"<p>Nous recherchons un responsable d\u2019atelier exp\u00e9riment\u00e9 pour piloter notre secteur de polissage bracelets. V\u00e9ritable garant de la qualit\u00e9 et de la performance de l\u2019atelier, vous jouerez un r\u00f4le central dans la ma\u00eetrise des finitions, la coordination des \u00e9quipes et l\u2019am\u00e9lioration continue des processus.<\/p>\n<p>Vos missions principales seront les suivantes: <\/p>\n<p>G\u00e9rer une \u00e9quipe de 40 collaborateurs<br \/>\nOrganiser les plannings et r\u00e9partir la charge<br \/>\nSuivre la production, \u00e9tablir et suivre les indicateurs cl\u00e9s de performance<br \/>\nG\u00e9rer la qualit\u00e9 et la conformit\u00e9 des normes et standards \u00e9tablis<br \/>\nProposer et impl\u00e9menter des actions d&#8217;am\u00e9lioration continue (Lean, 5S, ergonomie, m\u00e9thodologie, etc.)<br \/>\nG\u00e9rer les flux,  les OF,  les priorit\u00e9s et la logistique de l&#8217;atelier<br \/>\nGarantir les normes de s\u00e9curit\u00e9, d&#8217;environnement et d&#8217;ergonomie de l&#8217;atelier<\/p>\n<p>En rejoignant notre \u00e9quipe, vous jouerez un r\u00f4le essentiel dans :<\/p>\n<p>La qualit\u00e9 finale de nos produits.<br \/>\nLa performance globale de la production, gr\u00e2ce \u00e0 une meilleure ma\u00eetrise des flux et des d\u00e9lais.<br \/>\nLa transmission du savoir-faire et la progression technique des \u00e9quipes.<br \/>\nLa r\u00e9duction des co\u00fbts de non-qualit\u00e9 via une gestion rigoureuse et des standards ma\u00eetris\u00e9s.<br \/>\nL\u2019image de l&#8217;entreprise, en garantissant des finitions irr\u00e9prochables<\/p>\n<p>Vous \u00eates au b\u00e9n\u00e9fice: <\/p>\n<p>D&#8217;une exp\u00e9rience confirm\u00e9e en polissage de pi\u00e8ces haut de gamme et de tous types de mat\u00e9riaux (10 ans minimum).<br \/>\nD&#8217;une exp\u00e9rience confirm\u00e9e en management d&#8217;\u00e9quipes industrielles de grande taille (5 ans minimum).<br \/>\nDe comp\u00e9tences av\u00e9r\u00e9es de leadership, communication et organisation.<br \/>\nD&#8217;une solide connaissance des indicateurs cl\u00e9s de performance industriels.<br \/>\nD&#8217;une bonne ma\u00eetrise d&#8217;un ERP et des outils informatiques usuels.<br \/>\nD&#8217;une parfaite ma\u00eetrise de la langue fran\u00e7aise, tant \u00e0 l&#8217;oral qu&#8217;\u00e0 l&#8217;\u00e9crit. <\/p>\n<p>Un poste int\u00e9ressant au sein d&#8217;une \u00e9quipe dynamique et d&#8217;une entreprise moderne \u00e0 taille humaine, des perspectives de d\u00e9veloppement et des conditions de travail motivantes.<\/p>\n<p>Int\u00e9ress\u00e9-e? Nous attendons votre postulation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous recherchons un responsable d\u2019atelier exp\u00e9riment\u00e9 pour piloter notre secteur de polissage bracelets. V\u00e9ritable garant de la qualit\u00e9 et de la performance de l\u2019atelier, vous jouerez un r\u00f4le central dans la ma\u00eetrise des finitions, la coordination des \u00e9quipes et l\u2019am\u00e9lioration continue des processus. Vos missions principales seront les suivantes: G\u00e9rer une \u00e9quipe de 40 collaborateurs [&hellip;]<\/p>\n","protected":false},"author":0,"template":"","class_list":["post-12152","offresdemploi","type-offresdemploi","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Responsable atelier - Werthanor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Responsable atelier - Werthanor\" \/>\n<meta property=\"og:description\" content=\"Nous recherchons un responsable d\u2019atelier exp\u00e9riment\u00e9 pour piloter notre secteur de polissage bracelets. V\u00e9ritable garant de la qualit\u00e9 et de la performance de l\u2019atelier, vous jouerez un r\u00f4le central dans la ma\u00eetrise des finitions, la coordination des \u00e9quipes et l\u2019am\u00e9lioration continue des processus. Vos missions principales seront les suivantes: G\u00e9rer une \u00e9quipe de 40 collaborateurs [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/\" \/>\n<meta property=\"og:site_name\" content=\"Werthanor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/\",\"url\":\"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/\",\"name\":\"Responsable atelier - Werthanor\",\"isPartOf\":{\"@id\":\"https:\/\/werthanor.ch\/#website\"},\"datePublished\":\"2026-05-12T22:02:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Offres d'emploi\",\"item\":\"https:\/\/werthanor.ch\/offre-d-emploi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Responsable atelier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/werthanor.ch\/#website\",\"url\":\"https:\/\/werthanor.ch\/\",\"name\":\"Werthanor\",\"description\":\"Werthanor SA \u2013 Fabrication de boites, bracelets et fermoirs\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/werthanor.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Responsable atelier - Werthanor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/","og_locale":"en_US","og_type":"article","og_title":"Responsable atelier - Werthanor","og_description":"Nous recherchons un responsable d\u2019atelier exp\u00e9riment\u00e9 pour piloter notre secteur de polissage bracelets. V\u00e9ritable garant de la qualit\u00e9 et de la performance de l\u2019atelier, vous jouerez un r\u00f4le central dans la ma\u00eetrise des finitions, la coordination des \u00e9quipes et l\u2019am\u00e9lioration continue des processus. Vos missions principales seront les suivantes: G\u00e9rer une \u00e9quipe de 40 collaborateurs [&hellip;]","og_url":"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/","og_site_name":"Werthanor","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/","url":"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/","name":"Responsable atelier - Werthanor","isPartOf":{"@id":"https:\/\/werthanor.ch\/#website"},"datePublished":"2026-05-12T22:02:34+00:00","breadcrumb":{"@id":"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/werthanor.ch\/offre-d-emploi\/responsable-atelier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Offres d'emploi","item":"https:\/\/werthanor.ch\/offre-d-emploi\/"},{"@type":"ListItem","position":2,"name":"Responsable atelier"}]},{"@type":"WebSite","@id":"https:\/\/werthanor.ch\/#website","url":"https:\/\/werthanor.ch\/","name":"Werthanor","description":"Werthanor SA \u2013 Fabrication de boites, bracelets et fermoirs","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/werthanor.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/werthanor.ch\/en\/wp-json\/wp\/v2\/offresdemploi\/12152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/werthanor.ch\/en\/wp-json\/wp\/v2\/offresdemploi"}],"about":[{"href":"https:\/\/werthanor.ch\/en\/wp-json\/wp\/v2\/types\/offresdemploi"}],"wp:attachment":[{"href":"https:\/\/werthanor.ch\/en\/wp-json\/wp\/v2\/media?parent=12152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}